{"id":17713,"date":"2014-03-03T13:22:06","date_gmt":"2014-03-03T13:22:06","guid":{"rendered":"https:\/\/remstim.de\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/"},"modified":"2023-09-14T16:18:14","modified_gmt":"2023-09-14T16:18:14","slug":"lo-stress-nella-vita-quotidiana-cosa-possiamo-fare","status":"publish","type":"post","link":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/","title":{"rendered":"Lo stress nella vita quotidiana: cosa possiamo fare!"},"content":{"rendered":"<h1>Tra i fattori di stress della vita quotidiana, i nostri simili sono al primo posto.<\/h1>\n<p>Le altre persone sono perfettamente in grado di farci perdere l&#8217;equilibrio e di stressarci. Chi non conosce il capo che non si riesce mai ad accontentare o il vicino di casa che ama fare festa di notte e ci priva del sonno? Ma cos\u00ec come le persone possono infastidirci, anche gli altri hanno la capacit\u00e0 di salvarci dallo stress.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft wp-image-7480\" src=\"https:\/\/remstim.com\/wp-content\/uploads\/2014\/03\/EMDR-Geraet-REMSTIM-3000-gegen-Stress-im-Alltag-e1512730477990.jpg\" alt=\"Lo stress nella vita quotidiana: cosa possiamo fare!\" width=\"340\" height=\"227\">Il neuroendocrinologo americano Bruce McEwen ha studiato la questione. \u00c8 considerato uno dei principali ricercatori sullo stress del nostro tempo. Egli descrive il carico psicologico permanente dello stress sul nostro corpo come &#8220;carico allostatico&#8221;. Il fattore decisivo \u00e8 la perdita permanente dell&#8217;equilibrio interiore, della calma interiore, dell&#8217;omeostasi. L&#8217;omeostasi descrive lo stato in cui, in circostanze normali, non viviamo alcun momento orbitale, non apportiamo alcun aggiustamento alle circostanze e ci limitiamo a essere mentre non accade nulla di speciale. Tutti i processi neuronali, ormonali e cardiovascolari del corpo sono in uno stato normale. Se siamo messi alla prova e il nostro organismo deve adattarsi al cambiamento delle condizioni, McEwen parla di allostasi.<\/p>\n<p>L&#8217;informazione che il nostro cervello \u00e8 l&#8217;organo decisivo per lo stress non \u00e8 una novit\u00e0. Il nostro cervello scatena reazioni significative che mettono il nostro corpo in stato di massima allerta. Perch\u00e9 il nostro cervello interpreta l&#8217;ambiente e giudica ci\u00f2 che accade intorno a noi. Gi\u00e0 il filosofo greco Epitteto proclamava quasi 2000 anni fa che &#8220;non sono le cose a preoccuparci, ma le opinioni che abbiamo delle cose&#8221;.<\/p>\n<p>Una funzione importante \u00e8 attribuita a una regione del nostro cervello chiamata ippocampo, responsabile della memorizzazione e del ricordo degli eventi quotidiani. Quando siamo costantemente sotto stress, la nostra capacit\u00e0 di memoria si riduce all&#8217;estremo. Anche il processo di neurogenesi \u00e8 gravemente compromesso. Pertanto, in circostanze di stress, l&#8217;ippocampo non sviluppa pi\u00f9 nuove cellule nervose e connessioni. Chi \u00e8 costantemente stressato diventa letteralmente &#8220;pi\u00f9 stupido&#8221;.<\/p>\n<p>Fortunatamente, \u00e8 possibile osservare anche lo sviluppo opposto. Lo stress e le sue conseguenze possono essere combattuti con utili contromisure. Le attivit\u00e0 fisiche regolari, come il jogging, la bicicletta o la camminata veloce, nonch\u00e9 altri sport, contribuiscono a migliorare in modo significativo la neurogenesi.<\/p>\n<h2>L&#8217;auto-coaching con l&#8217;EMDR inizia direttamente con il fattore di stress.<\/h2>\n<p>\u00c8 ancora necessaria una certa pratica per l&#8217;auto-allenamento, anche se minima, perch\u00e9 sotto stress, prendere contromisure pu\u00f2 essere percepito come uno stress aggiuntivo. Pi\u00f9 semplice \u00e8 l&#8217;aiuto, meglio \u00e8. Per questo, gli occhiali EMDR <a title=\"Panoramica del prodotto REMSTIM 3000\" href=\"\/?page_id=3161\">REMSTIM 3000<\/a> sono particolarmente adatti a superare gli ostacoli interiori. Basta indossarlo e fare &#8220;clic&#8221;. 2-3 applicazioni e di solito la prima esuberante ondata di sentimenti si attenua. Respirare profondamente \u00e8 di nuovo possibile. Ora il lavoro pu\u00f2 essere proseguito in modo mirato. La prima domanda di una sessione di self-coaching \u00e8 quindi:<a title=\"Fase 1 dell'auto-coaching EMDR: Determinare il tema\" href=\"https:\/\/remstim.com\/it\/auto-allenamento-in-6-passi-con-lemdr-grazie-a-remstim-3000\/fase-1-dellauto-coaching-emdr-determinare-il-tema\/\">&#8220;Cosa ti emoziona di pi\u00f9 in questo momento?<\/a>&#8220;.<a title=\"Fase 1 dell'auto-coaching EMDR: Determinare il tema\" href=\"https:\/\/remstim.com\/it\/auto-allenamento-in-6-passi-con-lemdr-grazie-a-remstim-3000\/fase-1-dellauto-coaching-emdr-determinare-il-tema\/\">(continua<\/a>).<\/p>\n<p>Con l&#8217;aiuto delle <a title=\"Auto-allenamento in 6 passi con l'EMDR grazie a REMSTIM 3000\" href=\"https:\/\/remstim.com\/it\/auto-allenamento-in-6-passi-con-lemdr-grazie-a-remstim-3000\/\">6 fasi dell&#8217;EMDR self-coaching<\/a> siamo in grado di identificare e lavorare sul fattore di stress in modo immediato e diretto. \u00c8 importante capire che non deve essere un problema particolarmente stressante. In effetti, sono proprio i piccoli ma numerosi &#8220;disturbatori del buonumore&#8221; della vita quotidiana a rovinarci la giornata. Ecco perch\u00e9 \u00e8 ancora pi\u00f9 importante non ignorare questi piccoli disturbatori emotivi, ma prenderli per le corna e affrontarli. Perch\u00e9 voi siete la connessione con i nostri grandi &#8220;temi&#8221;, che attraverso di loro accedono segretamente alla nostra vita quotidiana. Pi\u00f9 queste piccole tracce di stress vengono individuate e neutralizzate nell&#8217;auto-allenamento e &#8220;reintegrate&#8221; nella nostra personalit\u00e0 come esperienze innocue, pi\u00f9 scopriamo la strada che porta alle radici del nostro stress. E poi, quando siamo pronti, li assumiamo.<\/p>\n<p>Ma non \u00e8 possibile senza stress. Da un lato, non si pu\u00f2 mai evitare del tutto; dall&#8217;altro, \u00e8 vitale, perch\u00e9 ci permette di affrontare i problemi e di risolverli, di concentrarci, di focalizzarci e di lottare per ci\u00f2 che \u00e8 importante per noi. Tossico e dannoso per la nostra salute \u00e8 quello che McEwen chiama stress che non si ferma perch\u00e9, ad esempio, le nostre circostanze sono caotiche, viviamo in povert\u00e0 o siamo esposti a incuria o abusi. I conflitti in corso esacerbano il nostro senso di stress. Diventa sempre pi\u00f9 pericoloso quando siamo esposti a queste situazioni e non abbiamo un supporto sociale. Gli esseri umani che ci sostengono e mostrano compassione rendono lo stress pi\u00f9 sopportabile. Senza incoraggiamento, il peso dei fattori di stress pu\u00f2 diventare schiacciante. A questo proposito, l&#8217;esclusione e il bullismo sono spesso fattori di stress con un elevato potenziale di malattia.<\/p>\n<p>Certamente, il nostro ambiente sociale \u00e8 spesso la prima causa di &#8220;carico allostatico&#8221;, ad esempio attraverso i conflitti interpersonali, la competizione sul lavoro, le dispute tra vicini e partner o la cura dei nostri cari. Ma come potrebbe essere altrimenti. Siamo esseri sociali. Pertanto, i nostri buoni contatti sociali possono fornirci l&#8217;affetto, l&#8217;amicizia, la collegialit\u00e0 e la comunit\u00e0 protettiva di cui abbiamo disperatamente bisogno per rendere lo stress sopportabile. La conoscenza del sostegno di una comunit\u00e0 solida ci rende pi\u00f9 resistenti allo stress.<\/p>\n<p>Hans Selye, creatore del concetto di stress, ci consigliava gi\u00e0 di lottare per l&#8217;affetto dei nostri simili per poter affrontare con forza lo stress del nostro mondo in rapida evoluzione.<\/p>\n<p><a href=\"https:\/\/remstim.com\/it\/remstim-3000\/\"><img decoding=\"async\" class=\"wp-image-3473 alignright\" src=\"https:\/\/remstim.com\/wp-content\/uploads\/2013\/06\/REMSTIM_3000_EMDR-Coaching_Geraet_7.jpg\" alt=\"Dispositivo di coaching EMDR REMSTIM 3000\" width=\"270\" height=\"203\" srcset=\"https:\/\/remstim.com\/wp-content\/uploads\/2013\/06\/REMSTIM_3000_EMDR-Coaching_Geraet_7.jpg 500w, https:\/\/remstim.com\/wp-content\/uploads\/2013\/06\/REMSTIM_3000_EMDR-Coaching_Geraet_7-300x225.jpg 300w\" sizes=\"(max-width: 270px) 100vw, 270px\" \/><\/a>In questo senso, il self-coaching \u00e8 il mezzo preferito per incontrare noi stessi. Lottiamo, per cos\u00ec dire, per noi stessi, per il nostro affetto verso noi stessi. Il self-coaching non \u00e8 solo intervento ma anche profilassi. L&#8217;uso regolare del dispositivo EMDR <a title=\"Panoramica del prodotto REMSTIM 3000\" href=\"\/?page_id=3161\">REMSTIM 3000<\/a> nei momenti in cui non \u00e8 presente un problema acuto aumenta la resistenza allo stress e fornisce una spina dorsale emotiva rafforzata nelle situazioni di stress. Osservazione frequente: la <a title=\"Movimenti oculari flessibili\" href=\"https:\/\/remstim.com\/it\/fondamenti-dellutilizzo-dellemdr-nel-coaching-con-il-remstim-3000\/movimenti-oculari-flessibili\/\">flessibilit\u00e0 dei nostri movimenti oculari<\/a> aumenta, cos\u00ec come la flessibilit\u00e0 della nostra costituzione mentale. Il nostro equilibrio mentale diventa pi\u00f9 equilibrato. Troviamo la nostra pace interiore sempre pi\u00f9 spesso e pi\u00f9 rapidamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tra i fattori di stress della vita quotidiana, i nostri simili sono al primo posto. Le altre persone sono perfettamente in grado di farci perdere l&#8217;equilibrio e di stressarci. Chi non conosce il capo che non si riesce mai ad accontentare o il vicino di casa che ama fare festa di notte e ci priva [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[809,827,816],"tags":[830,826,822,829,828,824],"class_list":["post-17713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lemdr-nel-coaching","category-lettera-di-coaching","category-lo-stress","tag-dispositivi-emdr","tag-dispositivo-antistress","tag-dispositivo-emdr-it","tag-lemdr-nel-coaching","tag-lo-stress","tag-occhiali-emdr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo stress nella vita quotidiana: cosa possiamo fare!<\/title>\n<meta name=\"description\" content=\"Tra i fattori di stress della vita quotidiana, i nostri simili sono al primo posto. Chi non conosce il capo che non si pu\u00f2 mai accontentare?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo stress nella vita quotidiana: cosa possiamo fare!\" \/>\n<meta property=\"og:description\" content=\"Tra i fattori di stress della vita quotidiana, i nostri simili sono al primo posto. Chi non conosce il capo che non si pu\u00f2 mai accontentare?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/\" \/>\n<meta property=\"og:site_name\" content=\"EMDR Ger\u00e4t REMSTIM 3000 gegen Stress\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-03T13:22:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-14T16:18:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/remstim.com\/wp-content\/uploads\/2014\/03\/EMDR-Geraet-REMSTIM-3000-gegen-Stress-im-Alltag-e1512730477990.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"283\" \/>\n\t<meta property=\"og:image:height\" content=\"283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thomas Buhl\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Buhl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/\"},\"author\":{\"name\":\"Thomas Buhl\",\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/#\\\/schema\\\/person\\\/7d000ba8e69d9f556f812d26f45c3f07\"},\"headline\":\"Lo stress nella vita quotidiana: cosa possiamo fare!\",\"datePublished\":\"2014-03-03T13:22:06+00:00\",\"dateModified\":\"2023-09-14T16:18:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/\"},\"wordCount\":964,\"publisher\":{\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/remstim.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/EMDR-Geraet-REMSTIM-3000-gegen-Stress-im-Alltag-e1512730477990.jpg\",\"keywords\":[\"Dispositivi EMDR\",\"Dispositivo antistress\",\"Dispositivo EMDR\",\"L'EMDR nel coaching\",\"Lo stress\",\"Occhiali EMDR\"],\"articleSection\":[\"L'EMDR nel coaching\",\"Lettera di coaching\",\"Lo stress\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/\",\"url\":\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/\",\"name\":\"Lo stress nella vita quotidiana: cosa possiamo fare!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/remstim.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/EMDR-Geraet-REMSTIM-3000-gegen-Stress-im-Alltag-e1512730477990.jpg\",\"datePublished\":\"2014-03-03T13:22:06+00:00\",\"dateModified\":\"2023-09-14T16:18:14+00:00\",\"description\":\"Tra i fattori di stress della vita quotidiana, i nostri simili sono al primo posto. Chi non conosce il capo che non si pu\u00f2 mai accontentare?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/remstim.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/EMDR-Geraet-REMSTIM-3000-gegen-Stress-im-Alltag-e1512730477990.jpg\",\"contentUrl\":\"https:\\\/\\\/remstim.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/EMDR-Geraet-REMSTIM-3000-gegen-Stress-im-Alltag-e1512730477990.jpg\",\"width\":283,\"height\":283},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/remstim.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo stress nella vita quotidiana: cosa possiamo fare!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/remstim.com\\\/it\\\/\",\"name\":\"EMDR Ger\u00e4t REMSTIM 3000 gegen Stress\",\"description\":\"Wie wir schnell Entspannung finden.\",\"publisher\":{\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/remstim.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/#organization\",\"name\":\"EMDR Ger\u00e4t REMSTIM 3000 gegen Stress\",\"url\":\"https:\\\/\\\/remstim.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/remstim.com\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/REMSTIM-Logo-mit-Untertitel_orange-e1340382850185.png\",\"contentUrl\":\"https:\\\/\\\/remstim.com\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/REMSTIM-Logo-mit-Untertitel_orange-e1340382850185.png\",\"width\":304,\"height\":80,\"caption\":\"EMDR Ger\u00e4t REMSTIM 3000 gegen Stress\"},\"image\":{\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/remstim.com\\\/it\\\/#\\\/schema\\\/person\\\/7d000ba8e69d9f556f812d26f45c3f07\",\"name\":\"Thomas Buhl\",\"url\":\"https:\\\/\\\/remstim.com\\\/it\\\/author\\\/wp_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo stress nella vita quotidiana: cosa possiamo fare!","description":"Tra i fattori di stress della vita quotidiana, i nostri simili sono al primo posto. Chi non conosce il capo che non si pu\u00f2 mai accontentare?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/","og_locale":"it_IT","og_type":"article","og_title":"Lo stress nella vita quotidiana: cosa possiamo fare!","og_description":"Tra i fattori di stress della vita quotidiana, i nostri simili sono al primo posto. Chi non conosce il capo che non si pu\u00f2 mai accontentare?","og_url":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/","og_site_name":"EMDR Ger\u00e4t REMSTIM 3000 gegen Stress","article_published_time":"2014-03-03T13:22:06+00:00","article_modified_time":"2023-09-14T16:18:14+00:00","og_image":[{"width":283,"height":283,"url":"https:\/\/remstim.com\/wp-content\/uploads\/2014\/03\/EMDR-Geraet-REMSTIM-3000-gegen-Stress-im-Alltag-e1512730477990.jpg","type":"image\/jpeg"}],"author":"Thomas Buhl","twitter_misc":{"Scritto da":"Thomas Buhl","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/#article","isPartOf":{"@id":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/"},"author":{"name":"Thomas Buhl","@id":"https:\/\/remstim.com\/it\/#\/schema\/person\/7d000ba8e69d9f556f812d26f45c3f07"},"headline":"Lo stress nella vita quotidiana: cosa possiamo fare!","datePublished":"2014-03-03T13:22:06+00:00","dateModified":"2023-09-14T16:18:14+00:00","mainEntityOfPage":{"@id":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/"},"wordCount":964,"publisher":{"@id":"https:\/\/remstim.com\/it\/#organization"},"image":{"@id":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/#primaryimage"},"thumbnailUrl":"https:\/\/remstim.com\/wp-content\/uploads\/2014\/03\/EMDR-Geraet-REMSTIM-3000-gegen-Stress-im-Alltag-e1512730477990.jpg","keywords":["Dispositivi EMDR","Dispositivo antistress","Dispositivo EMDR","L'EMDR nel coaching","Lo stress","Occhiali EMDR"],"articleSection":["L'EMDR nel coaching","Lettera di coaching","Lo stress"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/","url":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/","name":"Lo stress nella vita quotidiana: cosa possiamo fare!","isPartOf":{"@id":"https:\/\/remstim.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/#primaryimage"},"image":{"@id":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/#primaryimage"},"thumbnailUrl":"https:\/\/remstim.com\/wp-content\/uploads\/2014\/03\/EMDR-Geraet-REMSTIM-3000-gegen-Stress-im-Alltag-e1512730477990.jpg","datePublished":"2014-03-03T13:22:06+00:00","dateModified":"2023-09-14T16:18:14+00:00","description":"Tra i fattori di stress della vita quotidiana, i nostri simili sono al primo posto. Chi non conosce il capo che non si pu\u00f2 mai accontentare?","breadcrumb":{"@id":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/#primaryimage","url":"https:\/\/remstim.com\/wp-content\/uploads\/2014\/03\/EMDR-Geraet-REMSTIM-3000-gegen-Stress-im-Alltag-e1512730477990.jpg","contentUrl":"https:\/\/remstim.com\/wp-content\/uploads\/2014\/03\/EMDR-Geraet-REMSTIM-3000-gegen-Stress-im-Alltag-e1512730477990.jpg","width":283,"height":283},{"@type":"BreadcrumbList","@id":"https:\/\/remstim.com\/it\/lo-stress-nella-vita-quotidiana-cosa-possiamo-fare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/remstim.com\/it\/"},{"@type":"ListItem","position":2,"name":"Lo stress nella vita quotidiana: cosa possiamo fare!"}]},{"@type":"WebSite","@id":"https:\/\/remstim.com\/it\/#website","url":"https:\/\/remstim.com\/it\/","name":"EMDR Ger\u00e4t REMSTIM 3000 gegen Stress","description":"Wie wir schnell Entspannung finden.","publisher":{"@id":"https:\/\/remstim.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/remstim.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/remstim.com\/it\/#organization","name":"EMDR Ger\u00e4t REMSTIM 3000 gegen Stress","url":"https:\/\/remstim.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/remstim.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/remstim.com\/wp-content\/uploads\/2012\/06\/REMSTIM-Logo-mit-Untertitel_orange-e1340382850185.png","contentUrl":"https:\/\/remstim.com\/wp-content\/uploads\/2012\/06\/REMSTIM-Logo-mit-Untertitel_orange-e1340382850185.png","width":304,"height":80,"caption":"EMDR Ger\u00e4t REMSTIM 3000 gegen Stress"},"image":{"@id":"https:\/\/remstim.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/remstim.com\/it\/#\/schema\/person\/7d000ba8e69d9f556f812d26f45c3f07","name":"Thomas Buhl","url":"https:\/\/remstim.com\/it\/author\/wp_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/remstim.com\/it\/wp-json\/wp\/v2\/posts\/17713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/remstim.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/remstim.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/remstim.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/remstim.com\/it\/wp-json\/wp\/v2\/comments?post=17713"}],"version-history":[{"count":0,"href":"https:\/\/remstim.com\/it\/wp-json\/wp\/v2\/posts\/17713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/remstim.com\/it\/wp-json\/wp\/v2\/media\/17529"}],"wp:attachment":[{"href":"https:\/\/remstim.com\/it\/wp-json\/wp\/v2\/media?parent=17713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/remstim.com\/it\/wp-json\/wp\/v2\/categories?post=17713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/remstim.com\/it\/wp-json\/wp\/v2\/tags?post=17713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}